{"id":2481,"date":"2023-03-18T00:58:09","date_gmt":"2023-03-17T23:58:09","guid":{"rendered":"https:\/\/sueyingkoang.com\/?post_type=tribe_events&amp;p=2481"},"modified":"2023-03-18T00:58:09","modified_gmt":"2023-03-17T23:58:09","slug":"zum-wohl-js-bach-la-fenice","status":"publish","type":"tribe_events","link":"https:\/\/sueyingkoang.com\/en\/event\/zum-wohl-js-bach-la-fenice\/","title":{"rendered":"Zum Wohl, JS Bach ! La Fenice"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"template":"","meta":{"_EventAllDay":false,"_EventTimezone":"Europe\/Paris","_EventStartDate":"2021-09-04 20:00:00","_EventEndDate":"2021-09-04 20:00:00","_EventStartDateUTC":"2021-09-04 18:00:00","_EventEndDateUTC":"2021-09-04 18:00:00","_EventShowMap":true,"_EventShowMapLink":true,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"prefix","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[2484],"_EventVenueID":[2483],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[2],"class_list":["post-2481","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-concert-season-2021-2022","cat_concert-season-2021-2022"],"_links":{"self":[{"href":"https:\/\/sueyingkoang.com\/en\/wp-json\/wp\/v2\/tribe_events\/2481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sueyingkoang.com\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/sueyingkoang.com\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/sueyingkoang.com\/en\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/sueyingkoang.com\/en\/wp-json\/wp\/v2\/tribe_events\/2481\/revisions"}],"wp:attachment":[{"href":"https:\/\/sueyingkoang.com\/en\/wp-json\/wp\/v2\/media?parent=2481"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sueyingkoang.com\/en\/wp-json\/wp\/v2\/tags?post=2481"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/sueyingkoang.com\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=2481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}